
{"id":14043,"date":"2021-05-01T19:51:39","date_gmt":"2021-05-01T17:51:39","guid":{"rendered":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/?p=14043"},"modified":"2023-02-14T11:44:11","modified_gmt":"2023-02-14T10:44:11","slug":"traam-2021-communiquer-avec-un-masque","status":"publish","type":"post","link":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/traam-2021-communiquer-avec-un-masque\/","title":{"rendered":"\u00c9coGest Lyon : [TraAM 2021] Communiquer avec un masque"},"content":{"rendered":"<h2>Communiquer avec un masque<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-14126 alignright\" src=\"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-300x186.jpg 300w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-768x476.jpg 768w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-1024x634.jpg 1024w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-170x105.jpg 170w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-90x56.jpg 90w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-370x229.jpg 370w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne-714x442.jpg 714w, https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-content\/uploads\/2021\/05\/Photo-Traam-2021-H\u00e9l\u00e8ne.jpg 1739w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/h2>\n<p>Une exp\u00e9rimentation du <a href=\"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/le-groupe-academique-traam-ecogestion-lyon\/\">groupe TraAM EcoGestion Lyon<\/a> (2020-21).<br \/>Par <strong>H\u00e9l\u00e8ne Duvanel<\/strong> &#8211; LP Danielle Casanova, Givors (69)<\/p>\n<h3>R\u00e9sum\u00e9<\/h3>\n<p>Le port du masque perturbe la communication dans notre quotidien et\u00a0particuli\u00e8rement en classe. Les \u00e9l\u00e8ves ont du mal \u00e0 comprendre, se faire comprendre\u00a0et trouvent fatiguant de parler avec ce masque. \u200b\u00a0<\/p>\n<p>Les \u00e9l\u00e8ves ont demand\u00e9 des \u2018\u2019cours\u2019\u2019 pour apprendre \u00e0 communiquer avec un masque, conscients des enjeux aussi bien dans leur quotidien qu\u2019en classe ou lors de leurs stages en entreprise.<\/p>\n<p>Vid\u00e9o r\u00e9sum\u00e9 : <a href=\"https:\/\/youtu.be\/s6oGnCkT7Uw\">https:\/\/youtu.be\/s6oGnCkT7Uw<\/a><\/p>\n<h3>Contexte<\/h3>\n<p>L\u2019exp\u00e9rimentation est men\u00e9e sur 1 classe de 24 \u00e9l\u00e8ves de Premi\u00e8re Bac Pro M\u00e9tiers du Commerce et de la Vente.<\/p>\n<h3>Objectifs p\u00e9dagogiques<\/h3>\n<ul>\n<li>Am\u00e9liorer sa communication orale\u200b<\/li>\n<li>D\u00e9terminer et organiser les \u00e9tapes d&rsquo;un projet\u200b<\/li>\n<li>Cr\u00e9er des diaporamas collaboratifs<\/li>\n<\/ul>\n<h3>D\u00e9roul\u00e9<\/h3>\n<p>Une premi\u00e8re \u00e9tape a consist\u00e9 \u00e0 filmer les \u00e9l\u00e8ves dans le cadre d&rsquo;une\u00a0simulation d&rsquo;entretien de vente. Une grille d&rsquo;analyse a permis de mettre\u00a0en avant les r\u00e9ussites et les points d&rsquo;am\u00e9lioration n\u00e9cessaires au niveau\u00a0de la qualit\u00e9 de la communication.\u00a0<\/p>\n<p>Les \u00e9l\u00e8ves ont ensuite list\u00e9 les \u00e9l\u00e9ments n\u00e9cessaires \u00e0 une meilleure\u00a0communication avec un masque.\u00a0<\/p>\n<p>Ils se sont d\u2019abord interrog\u00e9s pour savoir pourquoi est-il difficile de\u00a0communiquer avec un masque. Le choix du masque\u00a0: en tissu, chirurgical, FFP3 &#8230; influe sur le confort de la communication. Certains masques donnant l\u2019impression de \u2018\u2019s\u2019\u00e9touffer\u2019\u2019 lorsque l\u2019on parle.<\/p>\n<p>Par la suite ils ont mis en avant l\u2019importance du non-verbal alors qu\u2019une partie du visage, masqu\u00e9e, ne peut plus exprimer certaines \u00e9motions. Ils ont \u00e9tudi\u00e9 un tableau pr\u00e9sentant toutes les \u00e9motions transmises par le regard. La gestuelle, la posture deviennent elles-aussi primordiales dans notre nouvelle communication.\u00a0\u00a0<\/p>\n<p>Des exercices d\u2019\u00e9locution et de respiration abdominale ont permis d\u2019apprendre \u00e0 moins se fatiguer et de parfaire la compr\u00e9hension de son interlocuteur.<\/p>\n<p>Enfin, lors de s\u00e9ances de co-intervention avec le professeur de fran\u00e7ais, il a \u00e9t\u00e9 propos\u00e9 de mettre en sc\u00e8ne diff\u00e9rents \u00e9changes professionnels en portant une attention particuli\u00e8re \u00e0 la tonalit\u00e9, l\u2019articulation, et l\u2019ensemble du non-verbal.<\/p>\n<p>Les sc\u00e8nes ont \u00e9t\u00e9 film\u00e9es pour permettre une analyse collective ou individuelle de la qualit\u00e9 de la communication avec un masque.<\/p>\n<h3>Mat\u00e9riel<\/h3>\n<p>L\u2019exp\u00e9rimentation se d\u00e9roule en classe groupe, dans une salle \u00e9quip\u00e9e de postes informatiques.<\/p>\n<ul>\n<li>Un \u00e9l\u00e8ve filme avec son smartphone les simulations d\u2019entretien de vente.<\/li>\n<li>Les vid\u00e9o sont pr\u00e9sent\u00e9es collectivement au vid\u00e9o-projecteur\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/li>\n<li>Recherche sur moteur de recherches<\/li>\n<li>Conception du diaporama collaboratif sur Google Slides<\/li>\n<li>Certains \u00e9l\u00e9ments sont pr\u00e9sent\u00e9s sous forme d\u2019infographie \u00e0 l\u2019aide de Canva<\/li>\n<\/ul>\n<h3>Avantages et limites du projet<\/h3>\n<h5>Avantages\u00a0:\u00a0<\/h5>\n<p>Ce projet pr\u00e9sente plusieurs avantages transposables dans diff\u00e9rentes mati\u00e8res :<\/p>\n<ul>\n<li>Encourager les \u00e9l\u00e8ves\/\u00e9tudiants \u00e0 utiliser la vid\u00e9o \u00e0 des fins d&rsquo;auto-\u00e9valuation.\u200b<\/li>\n<li>Permettre aux jeunes de progresser dans l&rsquo;acceptation de leur image, de leur voix au travers de la vid\u00e9o\u200b<\/li>\n<li>La diversit\u00e9 des outils num\u00e9riques utilis\u00e9s offre une panoplie d&rsquo;applications r\u00e9utilisables par les \u00e9l\u00e8ves dans de nouvelles circonstances p\u00e9dagogiques ou professionnelles.<\/li>\n<\/ul>\n<h5>Limites\u00a0:\u00a0<\/h5>\n<ul>\n<li>M\u00eame masqu\u00e9s, un grand nombre d\u2019\u00e9l\u00e8ves refuse d\u2019\u00eatre film\u00e9s. Ce sont bien souvent les \u00e9l\u00e8ves les plus \u00e0 l\u2019aise \u00e0 l\u2019oral qui se proposent d\u2019\u00eatre film\u00e9s.\u00a0\u00a0<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Communiquer avec un masque Une exp\u00e9rimentation du groupe TraAM EcoGestion Lyon (2020-21).Par H\u00e9l\u00e8ne Duvanel &#8211; LP Danielle Casanova, Givors (69) R\u00e9sum\u00e9 Le port du masque perturbe la communication dans notre quotidien et\u00a0particuli\u00e8rement en classe. Les \u00e9l\u00e8ves ont du mal \u00e0 comprendre, se faire comprendre\u00a0et trouvent fatiguant de parler avec ce masque. \u200b\u00a0 Les \u00e9l\u00e8ves ont [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":14127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[436],"tags":[483,485,486,497,599,600,602],"class_list":["post-14043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-traam","tag-traam","tag-experimentation","tag-numerique","tag-covid","tag-599","tag-oral","tag-masque"],"_links":{"self":[{"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/posts\/14043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/comments?post=14043"}],"version-history":[{"count":7,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/posts\/14043\/revisions"}],"predecessor-version":[{"id":14129,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/posts\/14043\/revisions\/14129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/media\/14127"}],"wp:attachment":[{"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/media?parent=14043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/categories?post=14043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecogestion-legt.enseigne.ac-lyon.fr\/legt\/wp-json\/wp\/v2\/tags?post=14043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}